{"id":43397,"date":"2024-03-28T04:45:49","date_gmt":"2024-03-27T21:45:49","guid":{"rendered":"https:\/\/stg.staffinc.co\/id-solution\/labor-supply\/idsolution-labor-supply-it-tech"},"modified":"2024-09-26T23:50:57","modified_gmt":"2024-09-26T16:50:57","slug":"it-and-tech","status":"publish","type":"page","link":"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech","title":{"rendered":"[ID]Solution &#8211; Labor Supply &#8211; IT &amp; Tech"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"43397\" class=\"elementor elementor-43397 elementor-38804\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-440ad13 e-flex e-con-boxed e-con e-parent\" data-id=\"440ad13\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bdfc94 elementor-mobile-align-center elementor-widget-mobile__width-initial elementor-hidden-desktop elementor-widget elementor-widget-breadcrumbs\" data-id=\"0bdfc94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/staffinc.co\/en\">Homepage<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39e1bb8 e-flex e-con-boxed e-con e-parent\" data-id=\"39e1bb8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d75c66a e-con-full e-flex e-con e-child\" data-id=\"d75c66a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a471d49 elementor-widget elementor-widget-heading\" data-id=\"a471d49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tech Roles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8df0c5f elementor-widget elementor-widget-heading\" data-id=\"8df0c5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">With great responsibility comes great technology<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cca8f6 elementor-widget elementor-widget-heading\" data-id=\"9cca8f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Learn how our IT and technology services solve real-world problems by building the right technology for your business<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cc51c1 elementor-widget elementor-widget-button\" data-id=\"1cc51c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact Sales<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-781575d e-con-full e-flex e-con e-child\" data-id=\"781575d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08cbb5f elementor-widget elementor-widget-image\" data-id=\"08cbb5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2144\" height=\"1544\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero.png\" class=\"attachment-full size-full wp-image-43121\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero.png 2144w, https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero-300x216.png 300w, https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero-1024x737.png 1024w, https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero-768x553.png 768w, https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero-1536x1106.png 1536w, https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero-2048x1475.png 2048w, https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero-800x576.png 800w\" sizes=\"(max-width: 2144px) 100vw, 2144px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5db4a2 e-flex e-con-boxed e-con e-parent\" data-id=\"e5db4a2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1424788 e-con-full e-flex e-con e-child\" data-id=\"1424788\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d301789 elementor-widget elementor-widget-image\" data-id=\"d301789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1677\" height=\"1257\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/1d261d396977f5417e528dcb78ca898a.jpeg\" class=\"attachment-full size-full wp-image-43120\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/1d261d396977f5417e528dcb78ca898a.jpeg 1677w, https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/1d261d396977f5417e528dcb78ca898a-300x225.jpeg 300w, https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/1d261d396977f5417e528dcb78ca898a-1024x768.jpeg 1024w, https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/1d261d396977f5417e528dcb78ca898a-768x576.jpeg 768w, https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/1d261d396977f5417e528dcb78ca898a-1536x1151.jpeg 1536w, https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/1d261d396977f5417e528dcb78ca898a-800x600.jpeg 800w\" sizes=\"(max-width: 1677px) 100vw, 1677px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a470ebd e-con-full e-flex e-con e-child\" data-id=\"a470ebd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb3f668 elementor-widget elementor-widget-heading\" data-id=\"bb3f668\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">What can you expect from our IT &amp; Tech service?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-599cf41 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"599cf41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Involves diverse responsibilities, network management to software develop<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Provides cost-effective access to expertise, scalability and risk mitigation<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Helping companies focus on core tasks and accelerate projects<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65e843e e-flex e-con-boxed e-con e-parent\" data-id=\"65e843e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-65efe64 e-flex e-con-boxed e-con e-child\" data-id=\"65efe64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c84f00 elementor-widget elementor-widget-heading\" data-id=\"2c84f00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IT Professionals that you can get from Staffinc<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c2f58a e-con-full e-flex e-con e-child\" data-id=\"1c2f58a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b06759c e-flex e-con-boxed e-con e-child\" data-id=\"b06759c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8a1f1ef e-con-full e-flex e-con e-child\" data-id=\"8a1f1ef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-dc61829 e-flex e-con-boxed e-con e-child\" data-id=\"dc61829\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8927edb elementor-widget elementor-widget-image\" data-id=\"8927edb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/04\/IT-and-Tech-Product-Management.svg\" title=\"IT and Tech \u2013 Product Management\" alt=\"IT and Tech - Product Management\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c3d7a52 e-con-full e-flex e-con e-child\" data-id=\"c3d7a52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b475d5f elementor-widget elementor-widget-heading\" data-id=\"b475d5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Product Management<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68d5a23 elementor-widget elementor-widget-heading\" data-id=\"68d5a23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Strong communication skills to collaborate with cross-functional teams and understand project needs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed001cb e-con-full e-flex e-con e-child\" data-id=\"ed001cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4a7e2ba e-flex e-con-boxed e-con e-child\" data-id=\"4a7e2ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-415573c elementor-widget elementor-widget-image\" data-id=\"415573c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/04\/IT-and-Tech-Solution-Mobile-Based-App-1.svg\" title=\"IT and Tech + Solution \u2013 Mobile Based App\" alt=\"IT and Tech + Solution - Mobile Based App\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ea4fcc e-con-full e-flex e-con e-child\" data-id=\"6ea4fcc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b3dc82 elementor-widget elementor-widget-heading\" data-id=\"3b3dc82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">(Mobile) App Developers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac7def elementor-widget elementor-widget-heading\" data-id=\"2ac7def\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Creative problem-solving skills and adaptability in the face of rapid technological change \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5507262 e-con-full e-flex e-con e-child\" data-id=\"5507262\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7228375 e-flex e-con-boxed e-con e-child\" data-id=\"7228375\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-860e234 elementor-widget elementor-widget-image\" data-id=\"860e234\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/04\/IT-and-Tech-Software-Developer-1.svg\" title=\"IT and Tech \u2013 Software Developer\" alt=\"IT and Tech - Software Developer\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53916f4 e-con-full e-flex e-con e-child\" data-id=\"53916f4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e803de7 elementor-widget elementor-widget-heading\" data-id=\"e803de7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Software Developers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d78df0 elementor-widget elementor-widget-heading\" data-id=\"3d78df0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Involves creating and maintaining software applications, utilizing various programming languages and frameworks<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d824ce4 e-flex e-con-boxed e-con e-child\" data-id=\"d824ce4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f027a1e e-con-full e-flex e-con e-child\" data-id=\"f027a1e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c40f7bd e-flex e-con-boxed e-con e-child\" data-id=\"c40f7bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5d0e1e elementor-widget elementor-widget-image\" data-id=\"c5d0e1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/04\/IT-and-Tech-IT-Solution-UI-UX-1-1.svg\" title=\"IT and Tech + IT Solution \u2013 UI UX\" alt=\"IT and Tech + IT Solution - UI UX\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-19361e3 e-con-full e-flex e-con e-child\" data-id=\"19361e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9eaf9e8 elementor-widget elementor-widget-heading\" data-id=\"9eaf9e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">UI\/UX Designer<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa25acf elementor-widget elementor-widget-heading\" data-id=\"fa25acf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sensitivity to user experience and ability to visualize intuitive and engaging design solutions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-661a940 e-con-full e-flex e-con e-child\" data-id=\"661a940\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7ec221c e-flex e-con-boxed e-con e-child\" data-id=\"7ec221c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2588127 elementor-widget elementor-widget-image\" data-id=\"2588127\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/04\/IT-and-Tech-Manual-QA-1.svg\" title=\"IT and Tech \u2013 Manual QA\" alt=\"IT and Tech - Manual QA\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69a1e46 e-con-full e-flex e-con e-child\" data-id=\"69a1e46\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3ee795 elementor-widget elementor-widget-heading\" data-id=\"e3ee795\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Manual Quality Assurance<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38b98d6 elementor-widget elementor-widget-heading\" data-id=\"38b98d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The role of Quality assurance is essential to ensure the quality and reliability of software products<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a561171 e-con-full e-flex e-con e-child\" data-id=\"a561171\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ab97708 e-flex e-con-boxed e-con e-child\" data-id=\"ab97708\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3e991b elementor-widget elementor-widget-image\" data-id=\"d3e991b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/04\/IT-and-Tech-Talent-Retention-1.svg\" title=\"IT and Tech \u2013 Talent Retention\" alt=\"IT and Tech - Talent Retention\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e49cbe e-con-full e-flex e-con e-child\" data-id=\"8e49cbe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-def0030 elementor-widget elementor-widget-heading\" data-id=\"def0030\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Talent Retention<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afefe1f elementor-widget elementor-widget-heading\" data-id=\"afefe1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Develop and implement strategies to motivate and retain the best talent in the organization \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0937822 e-con-full e-flex e-con e-child\" data-id=\"0937822\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a8af256 e-con-full e-flex e-con e-child\" data-id=\"a8af256\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6183178 e-flex e-con-boxed e-con e-child\" data-id=\"6183178\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-994f40a elementor-widget elementor-widget-image\" data-id=\"994f40a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/04\/IT-Tech-Automated-QA-1.svg\" title=\"IT &amp; Tech \u2013 Automated QA\" alt=\"IT &amp; Tech - Automated QA\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-224bedb e-con-full e-flex e-con e-child\" data-id=\"224bedb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c55d3af elementor-widget elementor-widget-heading\" data-id=\"c55d3af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Automation Quality Assurance<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d30b3f elementor-widget elementor-widget-heading\" data-id=\"1d30b3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Automate testing to improve testing efficiency and quality<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e19a207 e-flex e-con-boxed e-con e-child\" data-id=\"e19a207\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7e1b010 e-flex e-con-boxed e-con e-child\" data-id=\"7e1b010\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e0e0d4 elementor-widget elementor-widget-image\" data-id=\"3e0e0d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/04\/IT-and-Tech-IT-Admins-1.svg\" title=\"IT and Tech \u2013 IT Admins\" alt=\"IT and Tech - IT Admins\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a3eb23 e-con-full e-flex e-con e-child\" data-id=\"5a3eb23\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0566b8c elementor-widget elementor-widget-heading\" data-id=\"0566b8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IT Admins<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eea9cf6 elementor-widget elementor-widget-heading\" data-id=\"eea9cf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Good time management and thoroughness in maintaining and repairing technology infrastructure to support smooth operations<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-93a4df2 e-flex e-con-boxed e-con e-parent\" data-id=\"93a4df2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-36c3370 e-con-full e-flex e-con e-child\" data-id=\"36c3370\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31155d2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"31155d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A transparent and reliable workforce starts with us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-120e7c2 elementor-widget elementor-widget-heading\" data-id=\"120e7c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Here are some reasons to convince you<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ee66dc e-flex e-con-boxed e-con e-child\" data-id=\"8ee66dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b4d8ec7 e-con-full e-flex e-con e-child\" data-id=\"b4d8ec7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-76690e9 e-flex e-con-boxed e-con e-child\" data-id=\"76690e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a6cb19 elementor-widget elementor-widget-image\" data-id=\"0a6cb19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/08\/Frame-1518.svg\" title=\"Frame-1518\" alt=\"Frame-1518\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dd19754 e-con-full e-flex e-con e-child\" data-id=\"dd19754\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d121500 elementor-widget elementor-widget-heading\" data-id=\"d121500\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contract term<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea4e1bc elementor-widget elementor-widget-heading\" data-id=\"ea4e1bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The minimum contract period is 3 months to ensure any ongoing projects<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2f5c19 e-con-full e-flex e-con e-child\" data-id=\"f2f5c19\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-751fced e-flex e-con-boxed e-con e-child\" data-id=\"751fced\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a400924 elementor-widget elementor-widget-image\" data-id=\"a400924\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/elementor\/thumbs\/Artboard-15@2x-8-1-rb2c6gvgdqopod5ptsm68talwr1e6arw8rygar9uco.png\" title=\"Artboard-15@2x-8-1.png\" alt=\"Artboard-15@2x-8-1.png\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9902ef e-con-full e-flex e-con e-child\" data-id=\"a9902ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40c56e9 elementor-widget elementor-widget-heading\" data-id=\"40c56e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SLA fast candidate delivery time \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4905634 elementor-widget elementor-widget-heading\" data-id=\"4905634\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">7 - 10 days valid for candidate submission time per project<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0fc7ac0 e-con-full e-flex e-con e-child\" data-id=\"0fc7ac0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0eeae09 e-flex e-con-boxed e-con e-child\" data-id=\"0eeae09\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9e8bbd elementor-widget elementor-widget-image\" data-id=\"e9e8bbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/elementor\/thumbs\/Artboard-16@2x-8-1-rb2c6fxm6wnfcr72za7jobj5bd60ylo5wnaythb8iw.png\" title=\"Artboard-16@2x-8-1.png\" alt=\"Artboard-16@2x-8-1.png\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c2acfa4 e-con-full e-flex e-con e-child\" data-id=\"c2acfa4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35a42c3 elementor-widget elementor-widget-heading\" data-id=\"35a42c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Timely payroll service<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d6e3d1 elementor-widget elementor-widget-heading\" data-id=\"7d6e3d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our payroll assistance includes the calculation of compensation and benefits<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d9a224 e-flex e-con-boxed e-con e-parent\" data-id=\"3d9a224\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9f4bc8 elementor-widget elementor-widget-heading\" data-id=\"a9f4bc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">What they say about Staffinc<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d2c61d slider-worker elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"7d2c61d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;2&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"43614\" class=\"elementor elementor-43614 elementor-8147 elementor-8147\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d72c339 e-flex e-con-boxed e-con e-parent\" data-id=\"d72c339\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03b902d elementor-widget elementor-widget-image\" data-id=\"03b902d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"129\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-1024x165.png\" class=\"attachment-large size-large wp-image-42273\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-1024x165.png 1024w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-800x129.png 800w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-300x48.png 300w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-768x124.png 768w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-1536x248.png 1536w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-2048x330.png 2048w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-18x3.png 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4372712 elementor-widget elementor-widget-text-editor\" data-id=\"4372712\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cWe are excited to collaborate with Staffinc (formerly Sampingan). They are very flexible and can adapt to our company\u2019s dynamic workflow. The PIC is also responsive and helpful.\u201d<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef83415 elementor-widget elementor-widget-heading\" data-id=\"ef83415\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><b>Hendro Santoso<\/b><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d9aba6 elementor-widget elementor-widget-heading\" data-id=\"9d9aba6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Senior Procurement Manager<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"43616\" class=\"elementor elementor-43616 elementor-8150 elementor-8150\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b39bb4 e-flex e-con-boxed e-con e-parent\" data-id=\"1b39bb4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86d20e3 elementor-widget elementor-widget-image\" data-id=\"86d20e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"129\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-1024x165.png\" class=\"attachment-large size-large wp-image-42273\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-1024x165.png 1024w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-800x129.png 800w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-300x48.png 300w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-768x124.png 768w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-1536x248.png 1536w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-2048x330.png 2048w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Bukalapak_2020.svg_-18x3.png 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e62942 elementor-widget elementor-widget-text-editor\" data-id=\"8e62942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cWith the help of Staffinc (formerly Sampingan) our salary disbursement to employees is always accurate and on time, and it brings significant advantages to Beedoor (part of Bukalapak)\u201d<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00cfcc1 elementor-widget elementor-widget-heading\" data-id=\"00cfcc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><b>Kareem Pello<\/b><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f48434 elementor-widget elementor-widget-heading\" data-id=\"2f48434\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Senior Human Resources &amp; General Affairs Manager<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"43618\" class=\"elementor elementor-43618 elementor-8156 elementor-8156\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9324bcc e-flex e-con-boxed e-con e-parent\" data-id=\"9324bcc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7c27e9 elementor-widget elementor-widget-image\" data-id=\"b7c27e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/jdl.png\" class=\"attachment-large size-large wp-image-42277\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/jdl.png 500w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/jdl-300x169.png 300w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/jdl-18x10.png 18w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ea0dba elementor-widget elementor-widget-text-editor\" data-id=\"5ea0dba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cThanks to Staffinc (formerly Sampingan), especially for its daily worker\u2019s swift payment.\u201d<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8330798 elementor-widget elementor-widget-heading\" data-id=\"8330798\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><b>Christina Erriana Putri<\/b><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd7ad24 elementor-widget elementor-widget-heading\" data-id=\"fd7ad24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">People Partners Operations, Region Jawa Tengah - DIY<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4290946 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"4290946\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aaa6739 e-con-full e-flex e-con e-child\" data-id=\"aaa6739\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2964f38 elementor-widget elementor-widget-heading\" data-id=\"2964f38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our client<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a63f364 elementor-widget elementor-widget-heading\" data-id=\"a63f364\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Companies that have entrusted us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9457203 e-flex e-con-boxed e-con e-child\" data-id=\"9457203\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f8b9659 e-flex e-con-boxed e-con e-child\" data-id=\"f8b9659\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d448ad7 elementor-widget elementor-widget-image\" data-id=\"d448ad7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/realme-logo.png\" class=\"attachment-large size-large wp-image-42380\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/realme-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/realme-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc77152 e-flex e-con-boxed e-con e-child\" data-id=\"bc77152\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90e663f elementor-widget elementor-widget-image\" data-id=\"90e663f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ariston-logo.png\" class=\"attachment-large size-large wp-image-42356\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ariston-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ariston-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7fba7d e-flex e-con-boxed e-con e-child\" data-id=\"c7fba7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-964c958 elementor-widget elementor-widget-image\" data-id=\"964c958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/3-logo.png\" class=\"attachment-large size-large wp-image-42353\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/3-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/3-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a99f1ff e-flex e-con-boxed e-con e-child\" data-id=\"a99f1ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-93ff255 elementor-widget elementor-widget-image\" data-id=\"93ff255\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/indosat-logo.png\" class=\"attachment-large size-large wp-image-42369\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/indosat-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/indosat-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f4a7599 e-flex e-con-boxed e-con e-child\" data-id=\"f4a7599\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abe6ff9 elementor-widget elementor-widget-image\" data-id=\"abe6ff9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/danone-logo.png\" class=\"attachment-large size-large wp-image-42362\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/danone-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/danone-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce0a3b2 e-flex e-con-boxed e-con e-child\" data-id=\"ce0a3b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a446cf elementor-widget elementor-widget-image\" data-id=\"1a446cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/sampoerna-logo.png\" class=\"attachment-large size-large wp-image-42381\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/sampoerna-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/sampoerna-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a24e75 e-flex e-con-boxed e-con e-child\" data-id=\"7a24e75\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69e5441 elementor-widget elementor-widget-image\" data-id=\"69e5441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/unilever-logo.png\" class=\"attachment-large size-large wp-image-42386\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/unilever-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/unilever-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3963ca5 e-flex e-con-boxed e-con e-child\" data-id=\"3963ca5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-27df02e e-flex e-con-boxed e-con e-child\" data-id=\"27df02e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48f158a elementor-widget elementor-widget-image\" data-id=\"48f158a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/iqos-logo.png\" class=\"attachment-large size-large wp-image-42370\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/iqos-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/iqos-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30a94cb e-flex e-con-boxed e-con e-child\" data-id=\"30a94cb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c371b37 elementor-widget elementor-widget-image\" data-id=\"c371b37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/otsuka-logo.png\" class=\"attachment-large size-large wp-image-42377\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/otsuka-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/otsuka-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68f48f3 e-flex e-con-boxed e-con e-child\" data-id=\"68f48f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7c9cc3 elementor-widget elementor-widget-image\" data-id=\"b7c9cc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"503\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/bukalapak-logo.png\" class=\"attachment-large size-large wp-image-42361\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/bukalapak-logo.png 503w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/bukalapak-logo-300x143.png 300w\" sizes=\"(max-width: 503px) 100vw, 503px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b70856d e-flex e-con-boxed e-con e-child\" data-id=\"b70856d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-664c66c elementor-widget elementor-widget-image\" data-id=\"664c66c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/astro-logo.png\" class=\"attachment-large size-large wp-image-42357\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/astro-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/astro-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35ae7bc e-flex e-con-boxed e-con e-child\" data-id=\"35ae7bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07155aa elementor-widget elementor-widget-image\" data-id=\"07155aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/tokopedia-logo.png\" class=\"attachment-large size-large wp-image-42383\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/tokopedia-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/tokopedia-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-954b114 e-flex e-con-boxed e-con e-child\" data-id=\"954b114\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea409cf elementor-widget elementor-widget-image\" data-id=\"ea409cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ula-logo.png\" class=\"attachment-large size-large wp-image-42385\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ula-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ula-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-153a96d e-flex e-con-boxed e-con e-child\" data-id=\"153a96d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd013a8 elementor-widget elementor-widget-image\" data-id=\"bd013a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/xl-axiata-logo.png\" class=\"attachment-large size-large wp-image-42387\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/xl-axiata-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/xl-axiata-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92602c7 e-flex e-con-boxed e-con e-child\" data-id=\"92602c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-561606f e-flex e-con-boxed e-con e-child\" data-id=\"561606f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-203eb1c elementor-widget elementor-widget-image\" data-id=\"203eb1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/shopee-logo.png\" class=\"attachment-large size-large wp-image-42382\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/shopee-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/shopee-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c41ded6 e-flex e-con-boxed e-con e-child\" data-id=\"c41ded6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e82b281 elementor-widget elementor-widget-image\" data-id=\"e82b281\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Frame-499062422.png\" class=\"attachment-large size-large wp-image-42365\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Frame-499062422.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/Frame-499062422-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b1d86c e-flex e-con-boxed e-con e-child\" data-id=\"4b1d86c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e09234e elementor-widget elementor-widget-image\" data-id=\"e09234e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/mega-logo.png\" class=\"attachment-large size-large wp-image-42374\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/mega-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/mega-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5536e2 e-flex e-con-boxed e-con e-child\" data-id=\"b5536e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd34f95 elementor-widget elementor-widget-image\" data-id=\"fd34f95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/linkaja-logo.png\" class=\"attachment-large size-large wp-image-42373\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/linkaja-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/linkaja-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5bd6d5 e-flex e-con-boxed e-con e-child\" data-id=\"e5bd6d5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2afff5 elementor-widget elementor-widget-image\" data-id=\"b2afff5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/bri-logo.png\" class=\"attachment-large size-large wp-image-42359\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/bri-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/bri-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b23fd5c e-flex e-con-boxed e-con e-child\" data-id=\"b23fd5c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d112e5a elementor-widget elementor-widget-image\" data-id=\"d112e5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/briventures-logo.png\" class=\"attachment-large size-large wp-image-42360\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/briventures-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/briventures-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-335d4ca e-flex e-con-boxed e-con e-child\" data-id=\"335d4ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e9ff9b elementor-widget elementor-widget-image\" data-id=\"3e9ff9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ag-logo.png\" class=\"attachment-large size-large wp-image-42354\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ag-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ag-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e75e9dd e-flex e-con-boxed e-con e-child\" data-id=\"e75e9dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3ef779c e-flex e-con-boxed e-con e-child\" data-id=\"3ef779c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c6908a elementor-widget elementor-widget-image\" data-id=\"8c6908a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/awantunai-logo.png\" class=\"attachment-large size-large wp-image-42358\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/awantunai-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/awantunai-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88a6fa7 e-flex e-con-boxed e-con e-child\" data-id=\"88a6fa7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1ad9b4 elementor-widget elementor-widget-image\" data-id=\"a1ad9b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/dhl-logo.png\" class=\"attachment-large size-large wp-image-42363\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/dhl-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/dhl-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee351b8 e-flex e-con-boxed e-con e-child\" data-id=\"ee351b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4e84d5 elementor-widget elementor-widget-image\" data-id=\"e4e84d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/gojek-logo.png\" class=\"attachment-large size-large wp-image-42366\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/gojek-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/gojek-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c5a03d9 e-flex e-con-boxed e-con e-child\" data-id=\"c5a03d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-445af4c elementor-widget elementor-widget-image\" data-id=\"445af4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/anteraja-logo.png\" class=\"attachment-large size-large wp-image-42355\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/anteraja-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/anteraja-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43e5838 e-flex e-con-boxed e-con e-child\" data-id=\"43e5838\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01b9fa0 elementor-widget elementor-widget-image\" data-id=\"01b9fa0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/j_t-logo.png\" class=\"attachment-large size-large wp-image-42371\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/j_t-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/j_t-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2773cac e-flex e-con-boxed e-con e-child\" data-id=\"2773cac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c7e2cb elementor-widget elementor-widget-image\" data-id=\"7c7e2cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ninjaexpress-logo.png\" class=\"attachment-large size-large wp-image-42376\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ninjaexpress-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/ninjaexpress-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-03792ab e-flex e-con-boxed e-con e-child\" data-id=\"03792ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebeb532 elementor-widget elementor-widget-image\" data-id=\"ebeb532\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/haus-logo.png\" class=\"attachment-large size-large wp-image-42368\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/haus-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/haus-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a5056c e-flex e-con-boxed e-con e-child\" data-id=\"8a5056c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2e3cca9 e-flex e-con-boxed e-con e-child\" data-id=\"2e3cca9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83ceea4 elementor-widget elementor-widget-image\" data-id=\"83ceea4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/kopikenangan-logo.png\" class=\"attachment-large size-large wp-image-42372\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/kopikenangan-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/kopikenangan-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef9bb28 e-flex e-con-boxed e-con e-child\" data-id=\"ef9bb28\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23088e9 elementor-widget elementor-widget-image\" data-id=\"23088e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/flashcoffee-logo.png\" class=\"attachment-large size-large wp-image-42364\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/flashcoffee-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/flashcoffee-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c85398 e-flex e-con-boxed e-con e-child\" data-id=\"0c85398\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7953f2a elementor-widget elementor-widget-image\" data-id=\"7953f2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/halodoc-logo.png\" class=\"attachment-large size-large wp-image-42367\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/halodoc-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/halodoc-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7225c80 e-flex e-con-boxed e-con e-child\" data-id=\"7225c80\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-602aecd elementor-widget elementor-widget-image\" data-id=\"602aecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/oyo-logo.png\" class=\"attachment-large size-large wp-image-42378\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/oyo-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/oyo-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6632be e-flex e-con-boxed e-con e-child\" data-id=\"e6632be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b080bc6 elementor-widget elementor-widget-image\" data-id=\"b080bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/molatv-logo.png\" class=\"attachment-large size-large wp-image-42375\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/molatv-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/molatv-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dabe231 e-flex e-con-boxed e-con e-child\" data-id=\"dabe231\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28f2de8 elementor-widget elementor-widget-image\" data-id=\"28f2de8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/printerous-logo.png\" class=\"attachment-large size-large wp-image-42379\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/printerous-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/printerous-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5be982 e-flex e-con-boxed e-con e-child\" data-id=\"e5be982\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6a7563 elementor-widget elementor-widget-image\" data-id=\"d6a7563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/traveloka-logo.png\" class=\"attachment-large size-large wp-image-42384\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/traveloka-logo.png 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/traveloka-logo-300x145.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90f69c6 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"90f69c6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6502ef7 e-con-full e-flex e-con e-child\" data-id=\"6502ef7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60ed8b2 elementor-widget elementor-widget-heading\" data-id=\"60ed8b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our client<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8675ff0 elementor-widget elementor-widget-heading\" data-id=\"8675ff0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Companies that have entrusted us<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1519b3e logo-partner elementor-testimonial--align-left elementor-widget__width-inherit elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"1519b3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;1&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"13773\" class=\"elementor elementor-13773\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83422b1 e-flex e-con-boxed e-con e-parent\" data-id=\"83422b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d95b2d9 e-flex e-con-boxed e-con e-child\" data-id=\"d95b2d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8858417 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"8858417\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/realme-logo.webp\" class=\"attachment-large size-large wp-image-49065\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/realme-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/realme-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-510592b e-flex e-con-boxed e-con e-child\" data-id=\"510592b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c643e15 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"c643e15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ariston-logo.webp\" class=\"attachment-large size-large wp-image-49081\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ariston-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ariston-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-86fc8fe e-flex e-con-boxed e-con e-child\" data-id=\"86fc8fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b56a29f elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"b56a29f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/3-logo.webp\" class=\"attachment-large size-large wp-image-49043\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/3-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/3-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-552850d e-flex e-con-boxed e-con e-child\" data-id=\"552850d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44f4bec elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"44f4bec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/indosat-logo.webp\" class=\"attachment-large size-large wp-image-49041\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/indosat-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/indosat-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8209f6f e-flex e-con-boxed e-con e-child\" data-id=\"8209f6f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1555152 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"1555152\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/danone-logo.webp\" class=\"attachment-large size-large wp-image-49029\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/danone-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/danone-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d7a2b3e e-flex e-con-boxed e-con e-child\" data-id=\"d7a2b3e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6410140 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"6410140\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/elementor\/thumbs\/sampoerna-logo-e1771926239970-rjmchztredfy8r4xo24jfwwmv5ikykgf2p7kjxsmc2.webp\" title=\"sampoerna-logo\" alt=\"sampoerna-logo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-687da48 e-flex e-con-boxed e-con e-child\" data-id=\"687da48\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad268d9 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"ad268d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/unilever-logo.webp\" class=\"attachment-large size-large wp-image-49033\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/unilever-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/unilever-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"13781\" class=\"elementor elementor-13781\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31b1fe6 e-flex e-con-boxed e-con e-parent\" data-id=\"31b1fe6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4528e67 e-flex e-con-boxed e-con e-child\" data-id=\"4528e67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a6d26b elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"2a6d26b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/iqos-logo.webp\" class=\"attachment-large size-large wp-image-49079\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/iqos-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/iqos-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-edcdeb0 e-flex e-con-boxed e-con e-child\" data-id=\"edcdeb0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ae51f5 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"6ae51f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/otsuka-logo.webp\" class=\"attachment-large size-large wp-image-49077\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/otsuka-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/otsuka-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0095cd0 e-flex e-con-boxed e-con e-child\" data-id=\"0095cd0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65a4fbf elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"65a4fbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"143\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/bukalapak-logo-300x143.webp\" class=\"attachment-medium size-medium wp-image-49060\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/bukalapak-logo-300x143.webp 300w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/bukalapak-logo.webp 503w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-01af51b e-flex e-con-boxed e-con e-child\" data-id=\"01af51b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbd54d7 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"dbd54d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/astro-logo.webp\" class=\"attachment-large size-large wp-image-49037\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/astro-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/astro-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae2048e e-flex e-con-boxed e-con e-child\" data-id=\"ae2048e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90f00bc elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"90f00bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/tokopedia-logo.webp\" class=\"attachment-large size-large wp-image-49075\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/tokopedia-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/tokopedia-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5240b1 e-flex e-con-boxed e-con e-child\" data-id=\"b5240b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-370ab62 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"370ab62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ula-logo.webp\" class=\"attachment-large size-large wp-image-49073\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ula-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ula-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a07d39 e-flex e-con-boxed e-con e-child\" data-id=\"4a07d39\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f55e2a elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"2f55e2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/xl-axiata-logo.webp\" class=\"attachment-large size-large wp-image-49071\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/xl-axiata-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/xl-axiata-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"13787\" class=\"elementor elementor-13787\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-611de03 e-flex e-con-boxed e-con e-parent\" data-id=\"611de03\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d1db597 e-flex e-con-boxed e-con e-child\" data-id=\"d1db597\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e4931f elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"4e4931f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/shopee-logo.webp\" class=\"attachment-large size-large wp-image-49069\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/shopee-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/shopee-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d85c14 e-flex e-con-boxed e-con e-child\" data-id=\"3d85c14\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b48b538 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"b48b538\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/kredivo-logo.webp\" class=\"attachment-large size-large wp-image-49049\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/kredivo-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/kredivo-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe83d8e e-flex e-con-boxed e-con e-child\" data-id=\"fe83d8e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d32d78 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"8d32d78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/mega-logo.webp\" class=\"attachment-large size-large wp-image-49045\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/mega-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/mega-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bcdabd9 e-flex e-con-boxed e-con e-child\" data-id=\"bcdabd9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-906ae54 elementor-widget elementor-widget-image\" data-id=\"906ae54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/linkaja-logo.webp\" class=\"attachment-large size-large wp-image-49067\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/linkaja-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/linkaja-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53ee66f e-flex e-con-boxed e-con e-child\" data-id=\"53ee66f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1471cba elementor-widget elementor-widget-image\" data-id=\"1471cba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/bri-logo.webp\" class=\"attachment-large size-large wp-image-49083\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/bri-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/bri-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0cc5109 e-flex e-con-boxed e-con e-child\" data-id=\"0cc5109\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-459edab elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"459edab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/briventures-logo.webp\" class=\"attachment-large size-large wp-image-49031\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/briventures-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/briventures-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f49820 e-flex e-con-boxed e-con e-child\" data-id=\"4f49820\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af99ff4 elementor-widget elementor-widget-image\" data-id=\"af99ff4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ag-logo.webp\" class=\"attachment-large size-large wp-image-49103\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ag-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ag-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"13796\" class=\"elementor elementor-13796\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-580f6e8 e-flex e-con-boxed e-con e-parent\" data-id=\"580f6e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e5da03c e-flex e-con-boxed e-con e-child\" data-id=\"e5da03c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-935ac85 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"935ac85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/awantunai-logo.webp\" class=\"attachment-large size-large wp-image-49101\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/awantunai-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/awantunai-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3708e08 e-flex e-con-boxed e-con e-child\" data-id=\"3708e08\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-511673e elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"511673e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/dhl-logo.webp\" class=\"attachment-large size-large wp-image-49099\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/dhl-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/dhl-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-858d2bc e-flex e-con-boxed e-con e-child\" data-id=\"858d2bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-300705c elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"300705c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/gojek-logo.webp\" class=\"attachment-large size-large wp-image-49097\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/gojek-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/gojek-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70f3198 e-flex e-con-boxed e-con e-child\" data-id=\"70f3198\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-157e8ca elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"157e8ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/anteraja-logo.webp\" class=\"attachment-large size-large wp-image-49051\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/anteraja-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/anteraja-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2e1932 e-flex e-con-boxed e-con e-child\" data-id=\"f2e1932\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-175ec7e elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"175ec7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/j_t-logo.webp\" class=\"attachment-large size-large wp-image-49095\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/j_t-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/j_t-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f21a4f e-flex e-con-boxed e-con e-child\" data-id=\"9f21a4f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6658f9d elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"6658f9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ninjaexpress-logo.webp\" class=\"attachment-large size-large wp-image-49027\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ninjaexpress-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/ninjaexpress-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-344b819 e-flex e-con-boxed e-con e-child\" data-id=\"344b819\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbb74f1 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"dbb74f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/haus-logo.webp\" class=\"attachment-large size-large wp-image-49039\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/haus-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/haus-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"13803\" class=\"elementor elementor-13803\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1183cd3 e-flex e-con-boxed e-con e-parent\" data-id=\"1183cd3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7098a01 e-flex e-con-boxed e-con e-child\" data-id=\"7098a01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e83e09 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"2e83e09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/kopikenangan-logo.webp\" class=\"attachment-large size-large wp-image-49047\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/kopikenangan-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/kopikenangan-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af4be7e e-flex e-con-boxed e-con e-child\" data-id=\"af4be7e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb5a229 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"cb5a229\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/flashcoffee-logo.webp\" class=\"attachment-large size-large wp-image-49093\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/flashcoffee-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/flashcoffee-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f94c0d3 e-flex e-con-boxed e-con e-child\" data-id=\"f94c0d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e134ed elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"5e134ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/halodoc-logo.webp\" class=\"attachment-large size-large wp-image-49053\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/halodoc-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/halodoc-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ad96d1 e-flex e-con-boxed e-con e-child\" data-id=\"2ad96d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65021a2 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"65021a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/oyo-logo.webp\" class=\"attachment-large size-large wp-image-49091\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/oyo-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/oyo-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62151e5 e-flex e-con-boxed e-con e-child\" data-id=\"62151e5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa0cd3f elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"fa0cd3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/molatv-logo.webp\" class=\"attachment-large size-large wp-image-49089\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/molatv-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/molatv-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-503d259 e-flex e-con-boxed e-con e-child\" data-id=\"503d259\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d286e6 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"9d286e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/printerous-logo.webp\" class=\"attachment-large size-large wp-image-49087\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/printerous-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/printerous-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73701d7 e-flex e-con-boxed e-con e-child\" data-id=\"73701d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff85322 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"ff85322\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"240\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/traveloka-logo.webp\" class=\"attachment-large size-large wp-image-49085\" alt=\"\" srcset=\"https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/traveloka-logo.webp 496w, https:\/\/staffinc.co\/wp-content\/uploads\/2026\/02\/traveloka-logo-300x145.webp 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7da2b59 e-flex e-con-boxed e-con e-parent\" data-id=\"7da2b59\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-109274c e-con-full e-flex e-con e-child\" data-id=\"109274c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbaf5b6 elementor-widget elementor-widget-image\" data-id=\"dbaf5b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"518\" height=\"346\" src=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/04\/comparisons-object-05-1.svg\" class=\"attachment-full size-full wp-image-43245\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26c57fd e-con-full e-flex e-con e-child\" data-id=\"26c57fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f117ee1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f117ee1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Tech enabled outsourcing makes the dream work<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ff9c39 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"1ff9c39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our proprietary self-developed tech enables you to gain unrivaled transparency in managing and monitoring your workforce. Always included in every manpower we provide.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tech Roles With great responsibility comes great technology Learn how our IT and technology services solve real-world problems by building the right technology for your business Contact Sales What can you expect from our IT &amp; Tech service? Involves diverse responsibilities, network management to software develop Provides cost-effective access to expertise, scalability and risk mitigation [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"parent":44388,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-43397","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marketing &amp; Sales Outsourcing Company in Indonesia | Staffinc<\/title>\n<meta name=\"description\" content=\"Staffinc provides marketing &amp; sales outsourcing for companies in Indonesia. From SPG, SPB, to Sales Canvasser, consult your needs with Staffinc now.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marketing &amp; Sales Outsourcing Company in Indonesia | Staffinc\" \/>\n<meta property=\"og:description\" content=\"Staffinc provides marketing &amp; sales outsourcing for companies in Indonesia. From SPG, SPB, to Sales Canvasser, consult your needs with Staffinc now.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech\" \/>\n<meta property=\"og:site_name\" content=\"Staffinc\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T16:50:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/solutions\\\/white-collar\\\/it-and-tech\",\"url\":\"https:\\\/\\\/staffinc.co\\\/en\\\/solutions\\\/white-collar\\\/it-and-tech\",\"name\":\"Marketing & Sales Outsourcing Company in Indonesia | Staffinc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/solutions\\\/white-collar\\\/it-and-tech#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/solutions\\\/white-collar\\\/it-and-tech#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staffinc.co\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/hero.png\",\"datePublished\":\"2024-03-27T21:45:49+00:00\",\"dateModified\":\"2024-09-26T16:50:57+00:00\",\"description\":\"Staffinc provides marketing & sales outsourcing for companies in Indonesia. From SPG, SPB, to Sales Canvasser, consult your needs with Staffinc now.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/solutions\\\/white-collar\\\/it-and-tech#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staffinc.co\\\/en\\\/solutions\\\/white-collar\\\/it-and-tech\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/solutions\\\/white-collar\\\/it-and-tech#primaryimage\",\"url\":\"https:\\\/\\\/staffinc.co\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/hero.png\",\"contentUrl\":\"https:\\\/\\\/staffinc.co\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/hero.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/solutions\\\/white-collar\\\/it-and-tech#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staffinc.co\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solution\",\"item\":\"https:\\\/\\\/staffinc.co\\\/en\\\/solutions\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"White Collar\",\"item\":\"https:\\\/\\\/staffinc.co\\\/en\\\/solusi\\\/rekrut\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"IT & Tech\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/staffinc.co\\\/en\\\/\",\"name\":\"Staffinc.co\",\"description\":\"Solusi Outsourcing dan Ketenagakerjaan Indonesia\",\"publisher\":{\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/#organization\"},\"alternateName\":\"Staffinc.co\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staffinc.co\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/#organization\",\"name\":\"Staffinc Group\",\"alternateName\":\"Staffinc.co\",\"url\":\"https:\\\/\\\/staffinc.co\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staffinc.co\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/staffinc-07-1.png\",\"contentUrl\":\"https:\\\/\\\/staffinc.co\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/staffinc-07-1.png\",\"width\":119,\"height\":34,\"caption\":\"Staffinc Group\"},\"image\":{\"@id\":\"https:\\\/\\\/staffinc.co\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/id.linkedin.com\\\/company\\\/staffinc-group\",\"https:\\\/\\\/www.instagram.com\\\/staffinc.co\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marketing & Sales Outsourcing Company in Indonesia | Staffinc","description":"Staffinc provides marketing & sales outsourcing for companies in Indonesia. From SPG, SPB, to Sales Canvasser, consult your needs with Staffinc now.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech","og_locale":"en_US","og_type":"article","og_title":"Marketing & Sales Outsourcing Company in Indonesia | Staffinc","og_description":"Staffinc provides marketing & sales outsourcing for companies in Indonesia. From SPG, SPB, to Sales Canvasser, consult your needs with Staffinc now.","og_url":"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech","og_site_name":"Staffinc","article_modified_time":"2024-09-26T16:50:57+00:00","og_image":[{"url":"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech","url":"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech","name":"Marketing & Sales Outsourcing Company in Indonesia | Staffinc","isPartOf":{"@id":"https:\/\/staffinc.co\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech#primaryimage"},"image":{"@id":"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech#primaryimage"},"thumbnailUrl":"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero.png","datePublished":"2024-03-27T21:45:49+00:00","dateModified":"2024-09-26T16:50:57+00:00","description":"Staffinc provides marketing & sales outsourcing for companies in Indonesia. From SPG, SPB, to Sales Canvasser, consult your needs with Staffinc now.","breadcrumb":{"@id":"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech#primaryimage","url":"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero.png","contentUrl":"https:\/\/staffinc.co\/wp-content\/uploads\/2024\/03\/hero.png"},{"@type":"BreadcrumbList","@id":"https:\/\/staffinc.co\/en\/solutions\/white-collar\/it-and-tech#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staffinc.co\/en"},{"@type":"ListItem","position":2,"name":"Solution","item":"https:\/\/staffinc.co\/en\/solutions"},{"@type":"ListItem","position":3,"name":"White Collar","item":"https:\/\/staffinc.co\/en\/solusi\/rekrut"},{"@type":"ListItem","position":4,"name":"IT & Tech"}]},{"@type":"WebSite","@id":"https:\/\/staffinc.co\/en\/#website","url":"https:\/\/staffinc.co\/en\/","name":"Staffinc.co","description":"Solusi Outsourcing dan Ketenagakerjaan Indonesia","publisher":{"@id":"https:\/\/staffinc.co\/en\/#organization"},"alternateName":"Staffinc.co","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staffinc.co\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/staffinc.co\/en\/#organization","name":"Staffinc Group","alternateName":"Staffinc.co","url":"https:\/\/staffinc.co\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/staffinc.co\/en\/#\/schema\/logo\/image\/","url":"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/staffinc-07-1.png","contentUrl":"https:\/\/staffinc.co\/wp-content\/uploads\/2023\/09\/staffinc-07-1.png","width":119,"height":34,"caption":"Staffinc Group"},"image":{"@id":"https:\/\/staffinc.co\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/id.linkedin.com\/company\/staffinc-group","https:\/\/www.instagram.com\/staffinc.co"]}]}},"_links":{"self":[{"href":"https:\/\/staffinc.co\/en\/wp-json\/wp\/v2\/pages\/43397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staffinc.co\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staffinc.co\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staffinc.co\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/staffinc.co\/en\/wp-json\/wp\/v2\/comments?post=43397"}],"version-history":[{"count":0,"href":"https:\/\/staffinc.co\/en\/wp-json\/wp\/v2\/pages\/43397\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/staffinc.co\/en\/wp-json\/wp\/v2\/pages\/44388"}],"wp:attachment":[{"href":"https:\/\/staffinc.co\/en\/wp-json\/wp\/v2\/media?parent=43397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}